{"id":158708,"date":"2021-12-22T13:41:33","date_gmt":"2021-12-22T16:41:33","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=158708"},"modified":"2021-12-22T13:42:06","modified_gmt":"2021-12-22T16:42:06","slug":"se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/","title":{"rendered":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda"},"content":{"rendered":"<p>Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche.<\/p>\n<p>Encabezado por el secretario de Desarrollo Humano y Calidad de Vida Diego <a href=\"https:\/\/www.facebook.com\/diegorobbiani\">Robbiani<\/a> y la presidenta del HCD <a href=\"https:\/\/www.instagram.com\/ceciliakrivochen\/?hl=es-la\">Cecilia Krivochen<\/a>, el encuentro cont\u00f3 con la participaci\u00f3n de funcionarios\/as de diferentes \u00e1reas del Municipio y representantes de distintos sectores que forman parte en su labor cotidiana de la gran tarea que supone promover derechos.<\/p>\n<p>La intervenci\u00f3n pretendi\u00f3 hacer visible el derecho a disfrutar en paz y armon\u00eda de las celebraciones de todas las personas que por alg\u00fan motivo sufren hipersensibilidad auditiva y deben enfrentar momentos dif\u00edciles junto a sus familias para sobrellevar los efectos de la pirotecnia sonora y otros estruendos que impiden su tranquilidad y disfrute.<\/p>\n<p>De igual modo, las mascotas y animales que no pertenecen a una familia, deben afrontar enormes dificultades y se ven expuestos a un sufrimiento que los vulnera por completo.<\/p>\n<p>Si bien como sociedad hemos tenido avances junto a la normativa que se ha ido generando al respecto, es necesario hacer especial hincapi\u00e9 en el compromiso colectivo, que debe basarse en la posibilidad de pensar que todas las personas somos diferentes y los festejos deben ser inclusivos, respetando esta consigna.<\/p>\n<p>Es as\u00ed que, a modo de s\u00edmbolo y para materializar estos deseos que unen, los y las referentes y organizaciones presentes colocaron deseos en el \u00e1rbol navide\u00f1o: empat\u00eda, igualdad de oportunidades, amor, vejeces felices, ni\u00f1eces felices, dignidad, libertad, participaci\u00f3n, solidaridad, mascotas felices, protecci\u00f3n, respeto por la diversidad, inclusi\u00f3n y compromiso social.<\/p>\n<p>\u201cPara nosotros es una pol\u00edtica de Estado, sobre todo la prevenci\u00f3n y promoci\u00f3n. Agradezco a instituciones, padres, madres, funcionarios y funcionarias que forman parte de un equipo importante que trabaja en la promoci\u00f3n de derechos\u201d, sostuvo el secretario de Desarrollo Humano y Calidad de Vida Diego Robbiani.<\/p>\n<p>Asimismo indic\u00f3 que \u201cel objetivo de la campa\u00f1a se cumpli\u00f3. Llevamos adelante una campa\u00f1a muy linda. Conf\u00edo que en estas Fiestas vamos a celebrar con m\u00e1s luces y menos ruido. Es muy importante lo que hemos trabajado\u201d.<\/p>\n<p>Finalmente se colocaron fanales iluminados al pie del \u00e1rbol, en representaci\u00f3n del esp\u00edritu de la campa\u00f1a \u201cM\u00e1s luces, menos ruido\u201d.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/se-realizo-15\/\" rel=\"attachment wp-att-158710\"><img decoding=\"async\" class=\"alignnone size-large wp-image-158710\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-1-1024x684.jpg\" alt=\"Se realiz\u00f3 \" width=\"900\" height=\"601\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-1-1024x684.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-1-300x201.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-1-768x513.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-1-1536x1027.jpg 1536w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-1-2048x1369.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este&#8230;<\/p>\n","protected":false},"author":1,"featured_media":158709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":["https:\/\/www.instagram.com\/ceciliakrivochen\/?hl=es-la"],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo<\/title>\n<meta name=\"description\" content=\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche, encabezado por Robbiani.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo\" \/>\n<meta property=\"og:description\" content=\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche, encabezado por Robbiani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-22T16:41:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-22T16:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda\",\"datePublished\":\"2021-12-22T16:41:33+00:00\",\"dateModified\":\"2021-12-22T16:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\"},\"wordCount\":403,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\",\"name\":\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-12-22T16:41:33+00:00\",\"dateModified\":\"2021-12-22T16:42:06+00:00\",\"description\":\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche, encabezado por Robbiani.\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo","description":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche, encabezado por Robbiani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/","og_locale":"es_ES","og_type":"article","og_title":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo","og_description":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche, encabezado por Robbiani.","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-12-22T16:41:33+00:00","article_modified_time":"2021-12-22T16:42:06+00:00","og_image":[{"width":2560,"height":1711,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda","datePublished":"2021-12-22T16:41:33+00:00","dateModified":"2021-12-22T16:42:06+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/"},"wordCount":403,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/","name":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-12-22T16:41:33+00:00","dateModified":"2021-12-22T16:42:06+00:00","description":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda, fue este martes por la noche, encabezado por Robbiani.","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/se-realizo-una-intervencion-con-deseos-en-el-arbolito-del-paseo-jesus-mendia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Se realiz\u00f3 una intervenci\u00f3n con deseos en el arbolito del Paseo Jes\u00fas Mend\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",2560,1711,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-300x201.jpg",300,201,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-768x513.jpg",640,428,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-1024x684.jpg",640,428,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-768x513.jpg",768,513,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-1536x1027.jpg",1536,1027,true],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion-2048x1369.jpg",2048,1369,true],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",1264,845,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",1024,684,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",711,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",640,428,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/12\/Se-realizo-una-intervencion.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a>","tag_info":"Ciudad","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/158708"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=158708"}],"version-history":[{"count":3,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/158708\/revisions"}],"predecessor-version":[{"id":158713,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/158708\/revisions\/158713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/158709"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=158708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=158708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=158708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}