{"id":157185,"date":"2021-11-24T09:44:48","date_gmt":"2021-11-24T12:44:48","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=157185"},"modified":"2021-11-24T09:45:24","modified_gmt":"2021-11-24T12:45:24","slug":"el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/","title":{"rendered":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric"},"content":{"rendered":"<p>El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric, es en el marco del 154\u00b0 Aniversario de la ciudad de Olavarr\u00eda, el Consejo de Administraci\u00f3n de Coopelectric ha resuelto adherir al Decreto Municipal N\u00b0 3938\/21.<\/p>\n<p>Por tal motivo, la sede administrativa de Coopelectric ubicada en Belgrano 2850, la Oficina T\u00e9cnica de Obras Sanitarias situada en Av. Del Valle y Av. Pellegrini, la Oficina T\u00e9cnica de Energ\u00eda El\u00e9ctrica que funciona en<br \/>\nPelegrino y Maip\u00fa y las Delegaciones, permanecer\u00e1n cerradas y sin atenci\u00f3n al p\u00fablico.<\/p>\n<p>No obstante, en los sectores operativos de los Servicios de El\u00e9ctrico y Sanitario las guardias funcionar\u00e1n con normalidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric, es en el marco del&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,64],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric -\" \/>\n<meta property=\"og:description\" content=\"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric, es en el marco del...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-24T12:44:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-24T12:45:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2018\/08\/PARO2-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric\",\"datePublished\":\"2021-11-24T12:44:48+00:00\",\"dateModified\":\"2021-11-24T12:45:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas 2\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\",\"name\":\"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric -\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-24T12:44:48+00:00\",\"dateModified\":\"2021-11-24T12:45:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/","og_locale":"es_ES","og_type":"article","og_title":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric -","og_description":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric, es en el marco del...","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-24T12:44:48+00:00","article_modified_time":"2021-11-24T12:45:24+00:00","og_image":[{"width":667,"height":445,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2018\/08\/PARO2-1-1.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric","datePublished":"2021-11-24T12:44:48+00:00","dateModified":"2021-11-24T12:45:24+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/"},"wordCount":122,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas 2"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/","name":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric -","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-24T12:44:48+00:00","dateModified":"2021-11-24T12:45:24+00:00","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-jueves-sera-dia-no-laborable-para-empleados-de-coopelectric\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"El jueves ser\u00e1 d\u00eda no laborable para empleados de Coopelectric"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","ug_big":"","1536x1536":"","2048x2048":"","newsever-slider-full":"","newsever-featured":"","newsever-medium":"","web-stories-poster-portrait":"","web-stories-publisher-logo":"","web-stories-thumbnail":""},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas-2\/\" rel=\"category tag\">Destacadas 2<\/a>","tag_info":"Destacadas 2","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157185"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=157185"}],"version-history":[{"count":2,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157185\/revisions"}],"predecessor-version":[{"id":157187,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157185\/revisions\/157187"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=157185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=157185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=157185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}