{"id":157182,"date":"2021-11-23T20:58:34","date_gmt":"2021-11-23T23:58:34","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=157182"},"modified":"2021-11-23T21:11:23","modified_gmt":"2021-11-24T00:11:23","slug":"este-martes-comenzaron-los-hisopados-en-establecimientos-educativos","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/","title":{"rendered":"Este martes comenzaron los hisopados en establecimientos educativos"},"content":{"rendered":"<p>Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes, el inicio de la actividad fue en el Colegio Monse\u00f1or C\u00e9sar C\u00e1neva, en donde se realizaron 20 testeos y ninguno result\u00f3 positivo.<\/p>\n<p>Adem\u00e1s contin\u00faa el plan de vacunaci\u00f3n, este martes se aplicaron 455 dosis contra el Covid-19 a ni\u00f1as y ni\u00f1os de 3 a 17 a\u00f1os, sobre un total de 558 personas vacunadas. En el Centro Cultural Universitario aplicaron 92 dosis, de las cuales 4 corresponden a primer componente en mayores de 18 a\u00f1os, 11 primeras dosis en ni\u00f1as y ni\u00f1os de 3 a 11 a\u00f1os, 12 inoculaciones con primer componente en la franja etaria de 12 a 17 a\u00f1os, 11 segundas dosis en adultos, 10 segundas dosis en j\u00f3venes de 12 a 17 a\u00f1os, 22 segundo componente en ni\u00f1as y ni\u00f1os de 3 a 11 a\u00f1os y 22 terceras dosis; en el Servicio Territorial N\u00b02 fueron 288 las personas vacunadas, de ellas 11 corresponden a primeras dosis en adultos, 6 primeras dosis en menores de 3 a 11 a\u00f1os, 12 primer componente en la franja etaria de 12 a 17 a\u00f1os, 34 de segundo componente a menores de 3 a 11 a\u00f1os, 11 segundas dosis a mayores de 18 a\u00f1os, 168 de segundo componente en j\u00f3venes de 12 a 17 a\u00f1os, 70 aplicaciones de segundo componente en la franja etaria de 3 a 11 a\u00f1os, y 12 vecinas y vecinos fueron inoculados con terceras dosis; y en la Facultad de Ciencias de la Salud se inocularon 178 personas de las cuales 8 corresponden a primer componente en adultos, 22 aplicaciones de primer componente en menores de 3 a 11 a\u00f1os, 9 primeras dosis en j\u00f3venes de 12 a 17 a\u00f1os, 9 segundas dosis en mayores de 18 a\u00f1os, 70 aplicaciones de segundo componente en la franja etaria de 12 a 17 a\u00f1os, 43 segundas dosis en menores de 3 a 11 a\u00f1os, y 17 corresponden a terceras dosis.<\/p>\n<p>Asimismo, sigue desarroll\u00e1ndose la vacunaci\u00f3n libre de primeras y segundas dosis para mayores de 18 a\u00f1os que acrediten domicilio en la localidad present\u00e1ndose con su DNI en cualquiera de las postas de vacunaci\u00f3n (como toda segunda dosis libre, se debe cumplir el plazo estipulado entre vacunas).<\/p>\n<p>A la par, se recuerda que para obtener el turno de vacunaci\u00f3n a ni\u00f1os y ni\u00f1as de entre 3 y 11 a\u00f1os, se deber\u00e1n inscribir al igual que los menores de 12 a 17, a trav\u00e9s del sitio web www.vacunatepba.gba.gob.ar . Adem\u00e1s, se habilit\u00f3 la primera dosis libre para mayores de 12 con enfermedades preexistentes.<\/p>\n<p>En cuanto a las actividades preventivas que se realizan en el Centro Provincial de Testeos que funciona en las instalaciones del Club El Fort\u00edn (Urquiza 2980), de lunes a viernes de 8 a 12 hs, este martes se realizaron 11 hisopados a personas que se presentaron de manera espont\u00e1nea, de las cuales ninguno result\u00f3 positivo.<\/p>\n<p>Cualquier duda o consulta, podr\u00e1n acercarse a cualquiera de las tres postas: Servicio Territorial N\u00b02, Av. Alberdi 2543, de 8 a 18 hs; Facultad de Ciencias de la Salud, Merlo entre Av. Pringles y 9 de julio, de 8 a 18 hs, y en el Centro Cultural Universitario, San Martin 1955, de 8 a 18 Hs.<\/p>\n<p>Foto: archivo- ilustrativa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes, el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":143165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,64],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este martes comenzaron los hisopados en establecimientos educativos<\/title>\n<meta name=\"description\" content=\"Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este martes comenzaron los hisopados en establecimientos educativos\" \/>\n<meta property=\"og:description\" content=\"Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-23T23:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-24T00:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Este martes comenzaron los hisopados en establecimientos educativos\",\"datePublished\":\"2021-11-23T23:58:34+00:00\",\"dateModified\":\"2021-11-24T00:11:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas 2\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\",\"name\":\"Este martes comenzaron los hisopados en establecimientos educativos\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-23T23:58:34+00:00\",\"dateModified\":\"2021-11-24T00:11:23+00:00\",\"description\":\"Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este martes comenzaron los hisopados en establecimientos educativos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este martes comenzaron los hisopados en establecimientos educativos","description":"Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/","og_locale":"es_ES","og_type":"article","og_title":"Este martes comenzaron los hisopados en establecimientos educativos","og_description":"Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-23T23:58:34+00:00","article_modified_time":"2021-11-24T00:11:23+00:00","og_image":[{"width":1024,"height":685,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Este martes comenzaron los hisopados en establecimientos educativos","datePublished":"2021-11-23T23:58:34+00:00","dateModified":"2021-11-24T00:11:23+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/"},"wordCount":518,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas 2"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/","name":"Este martes comenzaron los hisopados en establecimientos educativos","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-23T23:58:34+00:00","dateModified":"2021-11-24T00:11:23+00:00","description":"Este martes comenzaron los hisopados en establecimientos educativos, fueron hisopados personal docente y estudiantes","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/este-martes-comenzaron-los-hisopados-en-establecimientos-educativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Este martes comenzaron los hisopados en establecimientos educativos"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",1024,685,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1-300x201.jpg",300,201,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1-768x514.jpg",640,428,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",640,428,false],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1-768x514.jpg",768,514,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",1024,685,false],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",1024,685,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",1024,685,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",1024,685,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",710,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",640,428,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/05\/Salud-RTA-Paseo-Salud-9-1024x685-1.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas-2\/\" rel=\"category tag\">Destacadas 2<\/a>","tag_info":"Destacadas 2","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157182"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=157182"}],"version-history":[{"count":1,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157182\/revisions"}],"predecessor-version":[{"id":157183,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157182\/revisions\/157183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/143165"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=157182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=157182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=157182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}