{"id":157088,"date":"2021-11-20T11:30:37","date_gmt":"2021-11-20T14:30:37","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=157088"},"modified":"2021-11-20T11:31:15","modified_gmt":"2021-11-20T14:31:15","slug":"finalizo-la-capacitacion-en-manejo-de-minicargador","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/","title":{"rendered":"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d"},"content":{"rendered":"<p>Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial que se lleva a cabo desde la Secretar\u00eda de Desarrollo Econ\u00f3mico-, culmin\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201c llevado a cabo en el Instituto Tecnol\u00f3gico Olavarr\u00eda (Iteco).<\/p>\n<p>Participaron de \u00e9sta capacitaci\u00f3n personal de empresas locales, personal de la planta de clasificaci\u00f3n del Proyecto Giro (Gesti\u00f3n Integral de Residuos Olavarr\u00eda) que est\u00e1 ubicada en el Relleno Sanitario e inscriptos en programa de capacitaci\u00f3n a trav\u00e9s del mail de la Secretar\u00eda de Desarrollo Econ\u00f3mico.<\/p>\n<p>A trav\u00e9s de la misma se han logrado competencias necesarias con respecto a puntos de seguridad, mantenimiento y operaci\u00f3n, realizando las pr\u00e1cticas de manejo de la maquinaria.<\/p>\n<p>El objetivo del \u201cPrograma integral de capacitaci\u00f3n para el sector minero e industrial\u201d es poder brindar herramientas formativas que potencien los perfiles del sector minero e industrial para la satisfactoria calificaci\u00f3n del personal y para el beneficio de la inserci\u00f3n laboral.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":157089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finaliz\u00f3 la capacitaci\u00f3n en &quot;Manejo de minicargador&quot;<\/title>\n<meta name=\"description\" content=\"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finaliz\u00f3 la capacitaci\u00f3n en &quot;Manejo de minicargador&quot;\" \/>\n<meta property=\"og:description\" content=\"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T14:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-20T14:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d\",\"datePublished\":\"2021-11-20T14:30:37+00:00\",\"dateModified\":\"2021-11-20T14:31:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\"},\"wordCount\":191,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\",\"name\":\"Finaliz\u00f3 la capacitaci\u00f3n en \\\"Manejo de minicargador\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-20T14:30:37+00:00\",\"dateModified\":\"2021-11-20T14:31:15+00:00\",\"description\":\"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial.\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finaliz\u00f3 la capacitaci\u00f3n en \"Manejo de minicargador\"","description":"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/","og_locale":"es_ES","og_type":"article","og_title":"Finaliz\u00f3 la capacitaci\u00f3n en \"Manejo de minicargador\"","og_description":"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial.","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-20T14:30:37+00:00","article_modified_time":"2021-11-20T14:31:15+00:00","og_image":[{"width":1772,"height":1181,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d","datePublished":"2021-11-20T14:30:37+00:00","dateModified":"2021-11-20T14:31:15+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/"},"wordCount":191,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/","name":"Finaliz\u00f3 la capacitaci\u00f3n en \"Manejo de minicargador\"","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-20T14:30:37+00:00","dateModified":"2021-11-20T14:31:15+00:00","description":"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d, en el marco del programa integral de capacitaci\u00f3n para el sector minero e industrial.","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/finalizo-la-capacitacion-en-manejo-de-minicargador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Finaliz\u00f3 la capacitaci\u00f3n en \u201cManejo de Minicargador\u201d"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",1772,1181,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en-300x200.jpg",300,200,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en-768x512.jpg",640,427,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en-1024x682.jpg",640,426,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en-768x512.jpg",768,512,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",1772,1181,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",1268,845,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",1024,682,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",713,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",640,427,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Finalizo-la-capacitacion-en.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a>","tag_info":"Ciudad","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157088"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=157088"}],"version-history":[{"count":1,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157088\/revisions"}],"predecessor-version":[{"id":157090,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/157088\/revisions\/157090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/157089"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=157088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=157088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=157088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}