{"id":156952,"date":"2021-11-19T10:20:41","date_gmt":"2021-11-19T13:20:41","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=156952"},"modified":"2021-11-19T10:21:06","modified_gmt":"2021-11-19T13:21:06","slug":"abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/","title":{"rendered":"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d"},"content":{"rendered":"<div class=\"page-title\">\n<p>Abuso en las infancias: <a href=\"https:\/\/www.facebook.com\/municipiodeolavarria\">Municipio <\/a>refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n del abuso sexual en las infancias que se recuerda cada 19 de noviembre, el Municipio de Olavarr\u00eda aprovecha la oportunidad para reforzar el mensaje de su campa\u00f1a de concientizaci\u00f3n \u201cAbramos los Ojos\u201d, que tiene como objetivo visibilizar la problem\u00e1tica del abuso sexual en las infancias y brindar informaci\u00f3n a la ciudadan\u00eda para prevenirlo.<\/p>\n<p>En el corto audiovisual realizado por los equipos de ni\u00f1eces municipales se presentan recomendaciones hacia las familias para detectarlo precozmente y actuar de manera urgente ante una presunci\u00f3n de abuso.<\/p>\n<p>Abuso en las infancias, Resume de manera detallada y precisa la informaci\u00f3n principal del concepto de abuso, brinda se\u00f1ales de alerta sobre signos y s\u00edntomas de esta problem\u00e1tica, consejos para ayudar a los ni\u00f1os y ni\u00f1as a poner en palabras lo que est\u00e1n sufriendo, y pautas generales para prevenirlo.<\/p>\n<p>Est\u00e1 disponible en el canal de Youtube oficial del Municipio, y se puede ver en el siguiente link.<\/p>\n<p>Desde el equipo de la Subsecretar\u00eda de Derechos, Igualdad y Oportunidades destacaron que \u201cel acceso a la informaci\u00f3n espec\u00edfica es fundamental para prevenir estas situaciones, como as\u00ed tambi\u00e9n, estar alertas en nuestros entornos cotidianos, en se\u00f1ales y cambios en los comportamientos, o ciertas conductas de los ni\u00f1os, ni\u00f1as o adolescentes, que puedan indicar la sospecha de abuso o maltrato\u00a8.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre la problem\u00e1tica o asesoramiento sobre situaciones puntuales de abuso en infancias, est\u00e1 disponible el n\u00famero de Guardia de Urgencias del Servicio Local de Promoci\u00f3n y Protecci\u00f3n de Derechos de Ni\u00f1os, Ni\u00f1as y Adolescentes: (02284) 15544810.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda&#8230;<\/p>\n","protected":false},"author":1,"featured_media":85689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abuso en las infancias: Municipio refuerza la campa\u00f1a de prevenci\u00f3n<\/title>\n<meta name=\"description\" content=\"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abuso en las infancias: Municipio refuerza la campa\u00f1a de prevenci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-19T13:20:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-19T13:21:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d\",\"datePublished\":\"2021-11-19T13:20:41+00:00\",\"dateModified\":\"2021-11-19T13:21:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\"},\"wordCount\":313,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\",\"name\":\"Abuso en las infancias: Municipio refuerza la campa\u00f1a de prevenci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-19T13:20:41+00:00\",\"dateModified\":\"2021-11-19T13:21:06+00:00\",\"description\":\"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abuso en las infancias: Municipio refuerza la campa\u00f1a de prevenci\u00f3n","description":"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/","og_locale":"es_ES","og_type":"article","og_title":"Abuso en las infancias: Municipio refuerza la campa\u00f1a de prevenci\u00f3n","og_description":"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-19T13:20:41+00:00","article_modified_time":"2021-11-19T13:21:06+00:00","og_image":[{"width":665,"height":417,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png","type":"image\/png"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d","datePublished":"2021-11-19T13:20:41+00:00","dateModified":"2021-11-19T13:21:06+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/"},"wordCount":313,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/","name":"Abuso en las infancias: Municipio refuerza la campa\u00f1a de prevenci\u00f3n","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-19T13:20:41+00:00","dateModified":"2021-11-19T13:21:06+00:00","description":"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d, en el d\u00eda Internacional para la prevenci\u00f3n","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/abuso-en-las-infancias-municipio-refuerza-campana-de-prevencion-abramos-los-ojos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Abuso en las infancias: Municipio refuerza campa\u00f1a de prevenci\u00f3n \u201cAbramos los ojos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL-150x150.png",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL-300x188.png",300,188,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",640,401,false],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",640,401,false],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",665,417,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",640,401,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",96,60,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/ABUSO-SEXUAL.png",150,94,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a>","tag_info":"Ciudad","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156952"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=156952"}],"version-history":[{"count":1,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156952\/revisions"}],"predecessor-version":[{"id":156953,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156952\/revisions\/156953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/85689"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=156952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=156952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=156952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}