{"id":156869,"date":"2021-11-17T14:56:41","date_gmt":"2021-11-17T17:56:41","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=156869"},"modified":"2021-11-17T15:00:55","modified_gmt":"2021-11-17T18:00:55","slug":"el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/","title":{"rendered":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio"},"content":{"rendered":"<p>El <a href=\"https:\/\/www.facebook.com\/CentroEmpleadosDeComercioDeOlavarria\">CECO<\/a> inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos por el D\u00eda de la Soberan\u00eda Nacional y adem\u00e1s inform\u00f3 que sus dependencias el s\u00e1bado 20 y el lunes 22 permanecer\u00e1n cerradas.<\/p>\n<p>El pr\u00f3ximo s\u00e1bado 20 ser\u00e1 feriado nacional por conmemorarse el D\u00eda de la Soberan\u00eda Nacional a 176 a\u00f1os de la Batalla de la Vuelta de Obligado. Tambi\u00e9n lo ser\u00e1 el lunes 22 que se estableci\u00f3 como feriado puente por decreto del Gobierno Nacional. En ambos casos rigen las normativas del descanso dominical.<\/p>\n<p>La \u201cLey de Contrato de Trabajo\u201d aclara que *feriado nacional* es una fecha que, por su vinculaci\u00f3n hist\u00f3rica, no se tiene que trabajar. En los d\u00edas feriados nacionales rigen las normas legales sobre el descanso dominical, y aquellos trabajadores que realicen sus tareas cobrar\u00e1n las horas al 100% y gozar\u00e1n de un franco compensatorio.<\/p>\n<p>El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, desde el sindicato informan que ambos d\u00edas sus dependencias permanecer\u00e1n\u00a0 cerradas y sin atenci\u00f3n al p\u00fablico. Lo mismo suceder\u00e1 en las oficinas de la obra social mercantil OSECAC y AMMBA, la farmacia sindical, el Gimnasio Funcional de CECO y los poli-consultorios ubicados en calle Moreno.<\/p>\n<p>Aquellos trabajadores mercantiles que deseen recibir m\u00e1s informaci\u00f3n o realizar alguna consulta al respecto pueden comunicarse a la Secretar\u00eda de Asuntos Gremiales del CECO en el horario de 8 a 16 horas telef\u00f3nicamente al 439300<br \/>\ninterno 425.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,64],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores<\/title>\n<meta name=\"description\" content=\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores\" \/>\n<meta property=\"og:description\" content=\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T17:56:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-17T18:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2018\/11\/ceco-e1543363208330.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio\",\"datePublished\":\"2021-11-17T17:56:41+00:00\",\"dateModified\":\"2021-11-17T18:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas 2\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\",\"name\":\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-17T17:56:41+00:00\",\"dateModified\":\"2021-11-17T18:00:55+00:00\",\"description\":\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores","description":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/","og_locale":"es_ES","og_type":"article","og_title":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores","og_description":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-17T17:56:41+00:00","article_modified_time":"2021-11-17T18:00:55+00:00","og_image":[{"width":800,"height":416,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2018\/11\/ceco-e1543363208330.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio","datePublished":"2021-11-17T17:56:41+00:00","dateModified":"2021-11-17T18:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/"},"wordCount":269,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas 2"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/","name":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-17T17:56:41+00:00","dateModified":"2021-11-17T18:00:55+00:00","description":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio, explicando el alcance de los mismos","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-ceco-informo-sobre-los-proximos-feriados-para-los-trabajadores-de-comercio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"El CECO inform\u00f3 sobre los pr\u00f3ximos feriados para los trabajadores de comercio"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","ug_big":"","1536x1536":"","2048x2048":"","newsever-slider-full":"","newsever-featured":"","newsever-medium":"","web-stories-poster-portrait":"","web-stories-publisher-logo":"","web-stories-thumbnail":""},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas-2\/\" rel=\"category tag\">Destacadas 2<\/a>","tag_info":"Destacadas 2","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156869"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=156869"}],"version-history":[{"count":3,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156869\/revisions"}],"predecessor-version":[{"id":156872,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156869\/revisions\/156872"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=156869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=156869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=156869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}