{"id":156804,"date":"2021-11-16T11:58:21","date_gmt":"2021-11-16T14:58:21","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=156804"},"modified":"2021-11-16T12:01:28","modified_gmt":"2021-11-16T15:01:28","slug":"puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/","title":{"rendered":"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha"},"content":{"rendered":"<p>Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano, se encuentra en marcha en la actualidad, con la finalidad de generar un espacio abierto, integrado al entorno natural del parque, con un dise\u00f1o totalmente moderno y confortable, principalmente.<\/p>\n<p>El intendente Ezequiel Galli \u2013en la ma\u00f1ana de este martes- recorri\u00f3 el sector de trabajo, acompa\u00f1ado por los secretarios de Salud Germ\u00e1n Caputo y de Mantenimiento y Obras P\u00fablicas Julio Ferraro.<\/p>\n<p>Como parte del proyecto, se busca que el lugar se consolide como un espacio destinado a la salud, no s\u00f3lo por las actividades propiamente dichas que se desarrollan en relaci\u00f3n a los controles m\u00e9dicos, sino tambi\u00e9n por la posibilidad que aporta para la realizaci\u00f3n de eventos relacionados a la actividad f\u00edsica y el bienestar de la poblaci\u00f3n.<\/p>\n<p>Mediante el dise\u00f1o se propone que el espacio sea un lugar de encuentro y reuni\u00f3n, con el equipamiento urbano necesario, adaptado a los requerimientos actuales de la comunidad.<\/p>\n<p>El acceso principal ser\u00e1 por la esquina de Belgrano y Avda. Brown, enmarcado por dos canteros elevados (situados sobre l\u00ednea municipal de dichas calles), que conducir\u00e1n a uno central, tambi\u00e9n elevado con un \u00fanico \u00e1rbol, que simbolizar\u00e1 la vida y el bienestar, para luego llegar al espacio f\u00edsico destinado a controles, que identificar\u00e1 al lugar como Paseo de la Salud.<\/p>\n<p>Cabe recordar, como antecedente, que el Paseo de la Salud fue inaugurado -el d\u00eda 10 de mayo de 2017- durante la gesti\u00f3n del intendente Ezequiel Galli, con dos objetivos claves: la promoci\u00f3n de h\u00e1bitos saludables y la prevenci\u00f3n de enfermedades no transmisibles.<\/p>\n<p>Puesta en valor del Paseo de la Salud, surgi\u00f3 por iniciativa de la Secretar\u00eda de Salud P\u00fablica y ha trabajado de manera multidisciplinaria y articulada con diferentes \u00e1reas como Bromatolog\u00eda, Deportes, Turismo, Cultura, en diferentes actividades, propuestas y campa\u00f1as de concientizaci\u00f3n, que tuvieron gran impacto en la comunidad.<\/p>\n<p>La obra de remodelaci\u00f3n del Paseo de la Salud \u2013fue licitada en el mes de julio en el Palacio San Mart\u00edn de la Municipalidad- con la participaci\u00f3n de tres empresas oferentes, resultando adjudicataria la firma de Jos\u00e9 Carlos Balzi, por un monto de $6.920.000.<\/p>\n<p>Los trabajos preliminares dieron inicio a fines del mes de agosto y en la actualidad la obra presenta un porcentaje de ejecuci\u00f3n que ronda el 40%, seg\u00fan la \u00faltima certificaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>16 noviembre, 2021 en C<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado&#8230;<\/p>\n","protected":false},"author":1,"featured_media":156805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,64],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Puesta en valor del paseo de la salud: la obra se encuentra en marcha<\/title>\n<meta name=\"description\" content=\"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puesta en valor del paseo de la salud: la obra se encuentra en marcha\" \/>\n<meta property=\"og:description\" content=\"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-16T14:58:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-16T15:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha\",\"datePublished\":\"2021-11-16T14:58:21+00:00\",\"dateModified\":\"2021-11-16T15:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\"},\"wordCount\":441,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas 2\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\",\"name\":\"Puesta en valor del paseo de la salud: la obra se encuentra en marcha\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-16T14:58:21+00:00\",\"dateModified\":\"2021-11-16T15:01:28+00:00\",\"description\":\"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano,\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puesta en valor del paseo de la salud: la obra se encuentra en marcha","description":"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/","og_locale":"es_ES","og_type":"article","og_title":"Puesta en valor del paseo de la salud: la obra se encuentra en marcha","og_description":"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano,","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-16T14:58:21+00:00","article_modified_time":"2021-11-16T15:01:28+00:00","og_image":[{"width":2560,"height":1711,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha","datePublished":"2021-11-16T14:58:21+00:00","dateModified":"2021-11-16T15:01:28+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/"},"wordCount":441,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas 2"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/","name":"Puesta en valor del paseo de la salud: la obra se encuentra en marcha","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-16T14:58:21+00:00","dateModified":"2021-11-16T15:01:28+00:00","description":"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha, ubicado en la esquina de Avda. Brown y Belgrano,","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/puesta-en-valor-del-paseo-de-la-salud-la-obra-se-encuentra-en-marcha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Puesta en valor del Paseo de la Salud: la obra se encuentra en marcha"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",2560,1711,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-300x201.jpg",300,201,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-768x513.jpg",640,428,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-1024x684.jpg",640,428,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-768x513.jpg",768,513,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-1536x1027.jpg",1536,1027,true],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del-2048x1369.jpg",2048,1369,true],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",1264,845,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",1024,684,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",711,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",640,428,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Puesta-en-valor-del.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas-2\/\" rel=\"category tag\">Destacadas 2<\/a>","tag_info":"Destacadas 2","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156804"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=156804"}],"version-history":[{"count":2,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156804\/revisions"}],"predecessor-version":[{"id":156808,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156804\/revisions\/156808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/156805"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=156804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=156804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=156804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}