{"id":156151,"date":"2021-11-06T12:30:41","date_gmt":"2021-11-06T15:30:41","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=156151"},"modified":"2021-11-06T12:35:32","modified_gmt":"2021-11-06T15:35:32","slug":"la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/","title":{"rendered":"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos"},"content":{"rendered":"<p>La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, el intendente Ezequiel <a href=\"https:\/\/www.facebook.com\/galliezequiel\">Galli<\/a> estuvo en el cuartel central de Bomberos Voluntarios para confirmar la realizaci\u00f3n de la 9\u00b0 edici\u00f3n de la Cena Anual Solidaria que en esta oportunidad ser\u00e1 en beneficio de la entidad.<\/p>\n<p>\u201cD\u00edas atr\u00e1s estuvimos con Hugo, Ra\u00fal, Guillermo en Loma Negra y me transmitieron una inquietud y posibilidad que ven\u00edan manejando hace tiempo de mudar el destacamento y surgi\u00f3 la posibilidad de hacer un cambio. El destacamento pasar\u00eda a ser del Municipio, a cambio de tierras m\u00e1s cerca de la ruta. Vamos a empezar a trabajar en papeles, enviarlo al HCD para que apruebe este cambio de tierras por destacamento\u201d, sostuvo el Intendente.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/la-novena\/\" rel=\"attachment wp-att-156156\"><img decoding=\"async\" class=\"alignnone size-large wp-image-156156\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-1024x684.jpg\" alt=\"La novena \" width=\"900\" height=\"601\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-1024x684.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-300x201.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-768x513.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-1536x1027.jpg 1536w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-2048x1369.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>Adem\u00e1s indic\u00f3 que \u201cel beneficio para Bomberos va a ser importante, van a tener un lugar m\u00e1s cerca de la ruta, como Bomberos y los vecinos de Loma Negra se merecen. Creo que va a ser un empuj\u00f3n importante. Estamos repitiendo la historia. Ya sucedi\u00f3 con Hinojo y esperamos que suceda lo mismo con Loma Negra\u201d.<\/p>\n<p>En este sentido se\u00f1al\u00f3 que Bomberos Voluntarios ser\u00e1 la instituci\u00f3n beneficiada en la 9\u00b0 edici\u00f3n de la Cena Anual Solidaria, que se realizar\u00e1 en el CEMO el pr\u00f3ximo 12 de febrero de 2022.<\/p>\n<p>Galli estuvo acompa\u00f1ado por el presidente de la Asociaci\u00f3n Hugo Fayan\u00e1s, el Jefe del Cuerpo Activo Ra\u00fal Ferreyra, el secretario de Desarrollo Humano y Calidad de Vida Diego Robbiani y el presidente del HCD Bruno Cenizo.<\/p>\n<p>Ferreyra manifest\u00f3 que \u201cpara nosotros decir gracias es habitual y es lo que corresponde cuando el vecino y las instituciones nos apoyan y dicen siempre presente para hacer aportes y que nosotros podamos invertir para que el servicio sea cada d\u00eda mejor y que nuestros bomberos puedan volver a sus casas sanos y salvos\u201d.<\/p>\n<p>\u201cCedernos en Loma negra un espacio f\u00edsico m\u00e1s amplio nos permitir\u00e1 construir un destacamento m\u00e1s moderno, funcional y grande. Lo de la cena me toma de sorpresa, pero para nosotros es un honor que nos haya elegido, porque hacemos mucho sacrificio. Esto nos cambia el horizonte, es un gran gesto y yo prometo que nos vamos a poner a trabajar lo m\u00e1s pronto posible\u201d, agreg\u00f3.<\/p>\n<p>Ferreyra pidi\u00f3 \u201ca toda la comunidad que nos acompa\u00f1e en esta cena para que la recaudaci\u00f3n sea lo m\u00e1s abultada posible y poder invertir para mejorar el servicio de Bomberos. Ayudar a Bomberos es pensar en la seguridad de todos nosotros. Estas obras son imposibles de hacerlas sin el apoyo del Estado y empresas\u201d.<\/p>\n<p>Finalmente, Hugo Fayan\u00e1s agradeci\u00f3 al Intendente y consider\u00f3 que \u201cera buena la noticia de entregar un predio que Loma Negra estaba necesitando desde hace un tiempo largo. La buena voluntad de Ezequiel para los Bomberos, que entendi\u00f3 r\u00e1pidamente. Tener esta posibilidad de poder contar con un destacamento nuevo. Uno tiene que estar a la altura para salir ante la emergencia. En el espacio nuevo vamos a hacer un destacamento acorde\u201d.<\/p>\n<p>\u201cEs un d\u00eda de festejo, el vecino de Loma se tiene que sentir contento de que vamos a tener un nuevo destacamento. Atr\u00e1s viene la noticia hermosa, nuestro agradecimiento eterno. Estamos bien perfilados, lo bueno de esta cena es que nos va a dar recursos suficientes como para arrancar esta obra. Estoy feliz de escuchar esta noticia. No tengas dudas que vamos a hacer una gran cena\u201d, asegur\u00f3 Fayan\u00e1s.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/cena-8\/\" rel=\"attachment wp-att-156157\"><img decoding=\"async\" class=\"alignnone size-large wp-image-156157\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/cena-1024x684.jpg\" alt=\"cena \" width=\"900\" height=\"601\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/cena-1024x684.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/cena-300x201.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/cena-768x513.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/cena-1536x1027.jpg 1536w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/cena-2048x1369.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":156152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,51],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La novena cena anual solidaria ser\u00e1 a beneficio de bomberos<\/title>\n<meta name=\"description\" content=\"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, Galli lo dijo en conferencia de prensa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La novena cena anual solidaria ser\u00e1 a beneficio de bomberos\" \/>\n<meta property=\"og:description\" content=\"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, Galli lo dijo en conferencia de prensa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-06T15:30:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-06T15:35:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos\",\"datePublished\":\"2021-11-06T15:30:41+00:00\",\"dateModified\":\"2021-11-06T15:35:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\"},\"wordCount\":601,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\",\"name\":\"La novena cena anual solidaria ser\u00e1 a beneficio de bomberos\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-06T15:30:41+00:00\",\"dateModified\":\"2021-11-06T15:35:32+00:00\",\"description\":\"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, Galli lo dijo en conferencia de prensa\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La novena cena anual solidaria ser\u00e1 a beneficio de bomberos","description":"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, Galli lo dijo en conferencia de prensa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/","og_locale":"es_ES","og_type":"article","og_title":"La novena cena anual solidaria ser\u00e1 a beneficio de bomberos","og_description":"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, Galli lo dijo en conferencia de prensa","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-06T15:30:41+00:00","article_modified_time":"2021-11-06T15:35:32+00:00","og_image":[{"width":2560,"height":1711,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos","datePublished":"2021-11-06T15:30:41+00:00","dateModified":"2021-11-06T15:35:32+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/"},"wordCount":601,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/","name":"La novena cena anual solidaria ser\u00e1 a beneficio de bomberos","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-06T15:30:41+00:00","dateModified":"2021-11-06T15:35:32+00:00","description":"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos,\u00a0 fue en la ma\u00f1ana de este s\u00e1bado, Galli lo dijo en conferencia de prensa","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-novena-cena-anual-solidaria-sera-a-beneficio-de-bomberos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"La novena Cena Anual Solidaria ser\u00e1 a beneficio de Bomberos"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",2560,1711,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-300x201.jpg",300,201,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-768x513.jpg",640,428,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-1024x684.jpg",640,428,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-768x513.jpg",768,513,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-1536x1027.jpg",1536,1027,true],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual-2048x1369.jpg",2048,1369,true],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",1264,845,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",1024,684,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",711,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",640,428,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/La-novena-Cena-Anual.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a>","tag_info":"Destacadas","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156151"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=156151"}],"version-history":[{"count":4,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156151\/revisions"}],"predecessor-version":[{"id":156158,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/156151\/revisions\/156158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/156152"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=156151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=156151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=156151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}