{"id":155913,"date":"2021-11-02T21:33:33","date_gmt":"2021-11-03T00:33:33","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=155913"},"modified":"2021-11-02T21:34:02","modified_gmt":"2021-11-03T00:34:02","slug":"el-programa-deconstruyendo-masculinidades-en-la-unidad-n2","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/","title":{"rendered":"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02"},"content":{"rendered":"<p>El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad y en especial a aquellos que han sido agresores para que reflexionen sobre tem\u00e1ticas de g\u00e9nero. Fueron ocho encuentros donde les brindaron herramientas a trav\u00e9s de un abordaje psicosocial y educativo a los 12 internos participantes. Trabajaron temas relacionados con la masculinidad.<\/p>\n<p>Trabajaron temas relacionados con la masculinidad hegem\u00f3nica y el camino hacia nuevas posibilidades de relaciones personales con el acento puesto en la construcci\u00f3n social del g\u00e9nero, para su reconstrucci\u00f3n consciente.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/el-programa-4\/\" rel=\"attachment wp-att-155915\"><img decoding=\"async\" class=\"alignnone size-large wp-image-155915\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-1024x768.jpg\" alt=\"El programa \" width=\"900\" height=\"675\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-1024x768.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-300x225.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-768x576.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa.jpg 1040w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>El espacio estuvo a cargo de la psic\u00f3loga y coordinadora t\u00e9cnica, Julieta Videla y el psicopedagogo, Gast\u00f3n Tolosa. Trabajaron con internos que tienen delitos asociados con violencia, integridad f\u00edsica contra la mujer o amenazas y fueron dispuestos por oficios judiciales. Los designados mostraron consentimiento en participar y tambi\u00e9n se incorporaron otros voluntariamente. Trabajaron mediante un dispositivo grupal con formato reflexivo y abordaron temas que refieren a diversidad sexual, de g\u00e9nero, perspectiva de g\u00e9nero, estereotipos, mandatos, violencia y roles. Cada clase con una duraci\u00f3n de hora y media, se dividi\u00f3 entre teor\u00eda, para adquirir los conceptos y pr\u00e1ctica que apunt\u00f3 a la reflexi\u00f3n a partir de utilizar cortometrajes, actividades l\u00fadicas, disparadores para pensar como<br \/>\nfrases y generar el espacio de debate.<\/p>\n<p>El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, los participantes que participaron del programa lo hicieron de una manera comprometida. \u201cHay dos listas de espera para hacer otros dos cursos. Al finalizar hacemos una evaluaci\u00f3n an\u00f3nima con m\u00faltiples respuestas para hacer un relevamiento de los conceptos adquiridos y lograr mejoras en el programa. Por otra parte, se anuncia al juzgado que entiende en la causa del interno su participaci\u00f3n mediante un certificado extendido por la Direcci\u00f3n de Lucha Contra las Violencias, de la Subsecretaria de Pol\u00edtica<br \/>\nCriminal\u201d, explic\u00f3 Videla.<\/p>\n<p>El equipo, a cargo del psicopedagogo Gast\u00f3n Tolosa y la psic\u00f3loga, coordinadora t\u00e9cnica Julieta Videla, recibieron la capacitaci\u00f3n de la Subsecretar\u00eda de Pol\u00edtica Criminal a cargo de Astrid Reyes y Clara Gallardo, quienes tambi\u00e9n acompa\u00f1aron en esta primera implementaci\u00f3n del Programa Deconstruyendo Masculinidades en la Unidad N\u00b02.<\/p>\n<p>\u201cLa experiencia con este grupo es muy buena, receptivos y respetuosos, gente que ha tenido dificultades, han cometido estos delitos, pudimos pensar por su obrar, pudimos referir que hay mandatos, estereotipos sociales que est\u00e1n arraigadas en la masculinidad y que la violencia est\u00e1 aceptada y legitimada en esos estereotipos. Es como se esperaba que ellos deb\u00edan reaccionar, han tenido una actitud de reflexi\u00f3n sobre un accionar que no fue el adecuado\u201d, destac\u00f3 Videla.<\/p>\n<p>Una vez finalizado el primer encuentro los participantes coincidieron en definir la experiencia como muy enriquecedora y vital para crecer como personas y mejorar sus relaciones interpersonales. Para Alberto, miembro<br \/>\ndel taller, \u201chay que aprender a respetar al otro\u201d. Por otra parte, Silvio reconoci\u00f3 que lo ayud\u00f3 \u201cmucho a entender la violencia y sus diferentes formas, entender la posici\u00f3n de la otra persona. Aprender de valores y darle la importancia necesaria a las cosas. Reconocer lo que puede pasar, las consecuencias, y eso nos ayuda a poner un freno, aprender hablar y escuchar. El curso nos ayuda a transmitirles estas ideas a otros y ayudarlos tambi\u00e9n, finaliz\u00f3.<\/p>\n<p>Fuente y Fotos: Servicio penitenciario bonaerense<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/deconstruyendo\/\" rel=\"attachment wp-att-155916\"><img decoding=\"async\" class=\"alignnone size-large wp-image-155916\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Deconstruyendo-1024x768.jpg\" alt=\"Deconstruyendo\" width=\"900\" height=\"675\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Deconstruyendo-1024x768.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Deconstruyendo-300x225.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Deconstruyendo-768x576.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/Deconstruyendo.jpg 1040w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":155914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El programa Deconstruyendo Masculinidades en la Unidad n\u00b02<\/title>\n<meta name=\"description\" content=\"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad especialmente a los agresores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El programa Deconstruyendo Masculinidades en la Unidad n\u00b02\" \/>\n<meta property=\"og:description\" content=\"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad especialmente a los agresores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-03T00:33:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-03T00:34:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02\",\"datePublished\":\"2021-11-03T00:33:33+00:00\",\"dateModified\":\"2021-11-03T00:34:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\"},\"wordCount\":576,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\",\"name\":\"El programa Deconstruyendo Masculinidades en la Unidad n\u00b02\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-11-03T00:33:33+00:00\",\"dateModified\":\"2021-11-03T00:34:02+00:00\",\"description\":\"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad especialmente a los agresores\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El programa Deconstruyendo Masculinidades en la Unidad n\u00b02","description":"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad especialmente a los agresores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/","og_locale":"es_ES","og_type":"article","og_title":"El programa Deconstruyendo Masculinidades en la Unidad n\u00b02","og_description":"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad especialmente a los agresores","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-11-03T00:33:33+00:00","article_modified_time":"2021-11-03T00:34:02+00:00","og_image":[{"width":1040,"height":780,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02","datePublished":"2021-11-03T00:33:33+00:00","dateModified":"2021-11-03T00:34:02+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/"},"wordCount":576,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/","name":"El programa Deconstruyendo Masculinidades en la Unidad n\u00b02","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-11-03T00:33:33+00:00","dateModified":"2021-11-03T00:34:02+00:00","description":"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02, destinado a los varones privados de la libertad especialmente a los agresores","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-programa-deconstruyendo-masculinidades-en-la-unidad-n2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"El programa Deconstruyendo Masculinidades en la Unidad N\u00b02"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",1040,780,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades-300x225.jpg",300,225,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades-768x576.jpg",640,480,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades-1024x768.jpg",640,480,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades-768x576.jpg",768,576,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",1040,780,false],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",1040,780,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",1040,780,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",1024,768,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",633,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",640,480,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",96,72,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/11\/El-programa-Deconstruyendo-Masculinidades.jpg",150,113,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a>","tag_info":"Ciudad","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/155913"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=155913"}],"version-history":[{"count":2,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/155913\/revisions"}],"predecessor-version":[{"id":155918,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/155913\/revisions\/155918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/155914"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=155913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=155913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=155913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}