{"id":154873,"date":"2021-10-19T17:46:23","date_gmt":"2021-10-19T20:46:23","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=154873"},"modified":"2021-10-19T17:59:39","modified_gmt":"2021-10-19T20:59:39","slug":"barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/","title":{"rendered":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas"},"content":{"rendered":"<p>Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas.<\/p>\n<p>El intendente Ezequiel Galli particip\u00f3 del acto de entrega de las \u00faltimas 16 viviendas del barrio UOCRA, que significa la concreci\u00f3n de un sue\u00f1o para las familias del sector, que a partir de ahora empiezan a construir su hogar.<\/p>\n<p>Fue por su decisi\u00f3n que se llevaron adelante en los \u00faltimos a\u00f1os una serie de gestiones ante el gobierno provincial, en distintas oportunidades, para la reactivaci\u00f3n de la obra, que estuvo paralizada durante mucho tiempo.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/barrio-5\/\" rel=\"attachment wp-att-154877\"><img decoding=\"async\" class=\"alignnone size-large wp-image-154877\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-1024x684.jpg\" alt=\"Barrio \" width=\"900\" height=\"601\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-1024x684.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-300x201.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-768x513.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-1536x1027.jpg 1536w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-2048x1369.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>Participaron en el acto, adem\u00e1s, el presidente del Honorable Concejo Deliberante Bruno Cenizo, el secretario de Desarrollo Humano y Calidad de Vida Diego Robbiani, el secretario de Gobierno Hilario Galli, el subsecretario de Legal y T\u00e9cnica Marcelo Fabbi y la directora de Casa de Tierras y Regularizaci\u00f3n Dominial Carolina Espinosa.<\/p>\n<p>Estuvieron presentes el administrador del Instituto de la Vivienda Agust\u00edn Simone, el subsecretario de Miner\u00eda de la provincia Federico Aguilera, los diputados Liliana Schwindt y C\u00e9sar Valicenti, el titular de Anses Maximiliano Wesner y la directora del Instituto de Vivienda de UOCRA Cristina Nieto.<\/p>\n<p>Tras las palabras de las autoridades, lleg\u00f3 el momento m\u00e1s esperado, la entrega de llaves y actas de adjudicaci\u00f3n de cada vivienda, donde cada familia comienza a vivir una nueva etapa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas. El intendente Ezequiel Galli particip\u00f3&#8230;<\/p>\n","protected":false},"author":1,"featured_media":154874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,51],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas<\/title>\n<meta name=\"description\" content=\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas, Ezequiel Galli particip\u00f3 del acto de entregas de viviendas en el barrio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas\" \/>\n<meta property=\"og:description\" content=\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas, Ezequiel Galli particip\u00f3 del acto de entregas de viviendas en el barrio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-19T20:46:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-19T20:59:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas\",\"datePublished\":\"2021-10-19T20:46:23+00:00\",\"dateModified\":\"2021-10-19T20:59:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\",\"name\":\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-10-19T20:46:23+00:00\",\"dateModified\":\"2021-10-19T20:59:39+00:00\",\"description\":\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas, Ezequiel Galli particip\u00f3 del acto de entregas de viviendas en el barrio.\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas","description":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas, Ezequiel Galli particip\u00f3 del acto de entregas de viviendas en el barrio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/","og_locale":"es_ES","og_type":"article","og_title":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas","og_description":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas, Ezequiel Galli particip\u00f3 del acto de entregas de viviendas en el barrio.","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-10-19T20:46:23+00:00","article_modified_time":"2021-10-19T20:59:39+00:00","og_image":[{"width":2560,"height":1711,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas","datePublished":"2021-10-19T20:46:23+00:00","dateModified":"2021-10-19T20:59:39+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/"},"wordCount":231,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/","name":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-10-19T20:46:23+00:00","dateModified":"2021-10-19T20:59:39+00:00","description":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas, Ezequiel Galli particip\u00f3 del acto de entregas de viviendas en el barrio.","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/barrio-uocra-galli-participo-del-acto-de-entrega-de-viviendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Barrio UOCRA: Galli particip\u00f3 del acto de entrega de viviendas"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",2560,1711,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-300x201.jpg",300,201,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-768x513.jpg",640,428,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-1024x684.jpg",640,428,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-768x513.jpg",768,513,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-1536x1027.jpg",1536,1027,true],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA-2048x1369.jpg",2048,1369,true],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",1264,845,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",1024,684,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",711,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",640,428,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Barrio-UOCRA.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a>","tag_info":"Destacadas","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154873"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=154873"}],"version-history":[{"count":3,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154873\/revisions"}],"predecessor-version":[{"id":154879,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154873\/revisions\/154879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/154874"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=154873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=154873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=154873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}