{"id":154642,"date":"2021-10-15T10:01:30","date_gmt":"2021-10-15T13:01:30","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=154642"},"modified":"2021-10-15T10:04:21","modified_gmt":"2021-10-15T13:04:21","slug":"el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/","title":{"rendered":"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales"},"content":{"rendered":"<p>El intendente Ezequiel <a href=\"https:\/\/www.facebook.com\/galliezequiel\">Galli<\/a> firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer.<\/p>\n<p>Estuvo acompa\u00f1ado por el secretario de Desarrollo Humano y Calidad de Vida Diego Robbiani y por la subsecretaria de Cultura y Educaci\u00f3n Agustina Marino.<\/p>\n<p>Tambi\u00e9n se hicieron presentes la decana de Sociales Gabriela Gamberini, el secretario de Extensi\u00f3n Nicol\u00e1s Casado, la coordinadora de Cultura Unicen Sof\u00eda Cheves y la coordinadora del CC Universitario Andrea Rivero.<\/p>\n<p>Tras dialogar sobre la actualidad de la casa de altos estudios y lo qu\u00e9 signific\u00f3 el paso de la pandemia, Diego Robbiani hizo hincapi\u00e9 en la \u201cnecesidad de tener un proyecto puntual en el \u00e1mbito de la cultura. La UNICEN trajo la propuesta de hacer una inversi\u00f3n en conjunto para financiar proyectos y colaborar con la cultura, que fue muy castigada en pandemia\u201d.<\/p>\n<p>Por su parte el intendente Galli destac\u00f3 que \u201ces fundamental el trabajo articulado que realizamos con UNICEN de manera permanente. Para el Municipio es clave\u201d<\/p>\n<p>Agustina Marino, subsecretaria de Cultura y Educaci\u00f3n, puntualiz\u00f3 en \u201cla informalidad que maneja el sector, que hace que artistas no se puedan presentar en becas por la cantidad de requisitos que les solicitan. Este acuerdo permite ahora realizar una selecci\u00f3n de mejores proyectos y un seguimiento en particular. Esta instancia va a estar buena para que puedan acceder a otros subsidios El acompa\u00f1amiento que vamos a hacer nos parece important\u00edsimo y adem\u00e1s nos deja un sondeo de los proyectos que est\u00e1n circulando en el sector y tener una perspectiva regional\u201d.<\/p>\n<p>Fondo reactivo cultural<\/p>\n<p>La propuesta se enmarca en el Programa EMERGER de la Universidad Nacional del Centro de la Provincia de Buenos Aires (UNICEN) coordinado por el \u00c1rea Cultura en el caso de Olavarr\u00eda a trav\u00e9s de la Facultad de Ciencias Sociales\/ Centro Cultural Universitario UNICEN.<\/p>\n<p>El Fondo Reactivo Cultural consiste en una convocatoria destinada a apoyar econ\u00f3micamente a Proyectos Art\u00edsticos Independientes con el fin de acompa\u00f1ar a las\/os trabajadoras\/es de la cultura de nuestra ciudad. En tal sentido, las propuestas ganadoras recibir\u00e1n un apoyo econ\u00f3mico extraordinario que constar\u00e1 de un pago \u00fanico de $30.000.<\/p>\n<p>Los proyectos, que podr\u00e1n presentar desde el 15 de octubre al 5 de noviembre del corriente a\u00f1o, deber\u00e1n ser desarrollados en nuestra ciudad y podr\u00e1n enmarcarse en las disciplinas artes esc\u00e9nicas, artes audiovisuales y multimediales, artes sonoras, literatura, artes visuales o interdisciplinarios.<\/p>\n<p>Los interesados pueden consultar formularios, bases y condiciones en www.olavarria.gov.ar y www.unicen.edu.ar<\/p>\n<p>Inscripci\u00f3n: https:\/\/docs.google.com\/forms\/d\/1_w7R8dLWjf9VwVaiLCYe3INTFxyz_oq9_maeppeu5mc\/edit?usp=drivesdk<\/p>\n<p>Por consultas comunicarse a: reactivocultural2021@gmail.com<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/el-intendente-ezequiel-2\/\" rel=\"attachment wp-att-154647\"><img decoding=\"async\" class=\"alignnone size-large wp-image-154647\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-Intendente-Ezequiel-1024x684.jpg\" alt=\"El Intendente Ezequiel\" width=\"900\" height=\"601\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-Intendente-Ezequiel-1024x684.jpg 1024w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-Intendente-Ezequiel-300x201.jpg 300w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-Intendente-Ezequiel-768x513.jpg 768w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-Intendente-Ezequiel-1536x1027.jpg 1536w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-Intendente-Ezequiel-2048x1369.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":154643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,51],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Intendente Ezequiel Galli firm\u00f3 un convenio con sociales<\/title>\n<meta name=\"description\" content=\"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer en la sala de reuniones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Intendente Ezequiel Galli firm\u00f3 un convenio con sociales\" \/>\n<meta property=\"og:description\" content=\"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer en la sala de reuniones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T13:01:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-15T13:04:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"765\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales\",\"datePublished\":\"2021-10-15T13:01:30+00:00\",\"dateModified\":\"2021-10-15T13:04:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\"},\"wordCount\":469,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\",\"name\":\"El Intendente Ezequiel Galli firm\u00f3 un convenio con sociales\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-10-15T13:01:30+00:00\",\"dateModified\":\"2021-10-15T13:04:21+00:00\",\"description\":\"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer en la sala de reuniones\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Intendente Ezequiel Galli firm\u00f3 un convenio con sociales","description":"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer en la sala de reuniones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/","og_locale":"es_ES","og_type":"article","og_title":"El Intendente Ezequiel Galli firm\u00f3 un convenio con sociales","og_description":"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer en la sala de reuniones","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-10-15T13:01:30+00:00","article_modified_time":"2021-10-15T13:04:21+00:00","og_image":[{"width":765,"height":511,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales","datePublished":"2021-10-15T13:01:30+00:00","dateModified":"2021-10-15T13:04:21+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/"},"wordCount":469,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/","name":"El Intendente Ezequiel Galli firm\u00f3 un convenio con sociales","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-10-15T13:01:30+00:00","dateModified":"2021-10-15T13:04:21+00:00","description":"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales,\u00a0 fue en la ma\u00f1ana de ayer en la sala de reuniones","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/el-intendente-ezequiel-galli-firmo-un-convenio-con-la-facultad-de-sociales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"El intendente Ezequiel Galli firm\u00f3 un convenio con la Facultad de Sociales"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",765,511,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-300x201.jpg",300,201,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-768x513.jpg",640,428,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-1024x684.jpg",640,428,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-768x513.jpg",768,513,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-1536x1027.jpg",1536,1027,true],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-2048x1369.jpg",2048,1369,true],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",765,511,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",765,511,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",711,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",640,428,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/El-intendente-Ezequiel-Galli-firmo-e1634302880230.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a>","tag_info":"Destacadas","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154642"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=154642"}],"version-history":[{"count":4,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154642\/revisions"}],"predecessor-version":[{"id":154648,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154642\/revisions\/154648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/154643"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=154642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=154642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=154642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}