{"id":154527,"date":"2021-10-13T20:08:31","date_gmt":"2021-10-13T23:08:31","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=154527"},"modified":"2021-10-13T20:43:44","modified_gmt":"2021-10-13T23:43:44","slug":"randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/","title":{"rendered":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel"},"content":{"rendered":"<p>Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se realiz\u00f3 una conferencia de prensa en el sal\u00f3n del Hotel Santa Rosa de la misma participaron Maricel Cides, Andrea Coronel, Florencio Randazzo y Carolina Castro.<\/p>\n<p>La primera en tomar la palabra fue Andrea Coronel &#8220;ac\u00e1 estamos seguimos adelante con este proyecto de Vamos con Vos, hoy tuvimos una reuni\u00f3n muy positiva que nos dan esas ganas de seguir estando en pol\u00edtica, pensar en lo que es la pol\u00edtica respecto a lo que es gesti\u00f3n, nos replanteamos muchas cosas, nos sirvi\u00f3 much\u00edsimo la charla que tuvimos en lo que tiene que ver con fiscalizaci\u00f3n, estrategias y tambi\u00e9n el an\u00e1lisis pol\u00edtico que hacemos en toda la provincia y en cada distrito. Nosotros le damos valor a la palabra le damos\u00a0 a cada uno de los habitantes, que conforman nuestra naci\u00f3n la importancia que se merece y queremos gestionar para la gente&#8221;.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/randazzo-estuvo-en-olavarria\/\" rel=\"attachment wp-att-154533\"><img decoding=\"async\" class=\"alignnone size-full wp-image-154533\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-estuvo-en-Olavarria.jpg\" alt=\"Randazzo estuvo en Olavarr\u00eda\" width=\"765\" height=\"510\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-estuvo-en-Olavarria.jpg 765w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-estuvo-en-Olavarria-300x200.jpg 300w\" sizes=\"(max-width: 765px) 100vw, 765px\" \/><\/a><\/p>\n<p>Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, &#8220;Agradecemos a Florencio porque son charlas que nos da y vamos a redoblar esa apuesta vamos a seguir adelante con este gran proyecto que no se termina en una elecci\u00f3n, esto va hacia futuro y estamos convencidos de que la gente va a ver hacia d\u00f3nde vamos, ni un lado ni del otro, de la gente de los problemas reales porque han metido a la sociedad en un pozo en el cual no puede salir y nosotros consideramos que la pol\u00edtica es una herramienta para transformar la vida de la gente, apostamos a esto y aquellos que no se presentaron a votar les decimos que est\u00e9n se presenten porque as\u00ed se hace la democracia yendo a votar&#8221;.<\/p>\n<p>Posteriormente habl\u00f3 Maricel Cides quien dijo &#8220;me sumo a las palabras de Andrea Coronel como candidata local agradeciendo esta posibilidad de reflexi\u00f3n y sobre todo por lo que esto implica nosotros sabemos y siempre lo hemos marcado la primera parte de la campa\u00f1a antes de las PASO que es un espacio pol\u00edtico, una tercera fuerza que se convoca en base a las voces no solo de quienes venimos de la pol\u00edtica y del peronismo sino tambi\u00e9n la gente de lo social, hay del partido socialista, vecinalistas y todo esto nos lleva a una riqueza en la discusi\u00f3n como la que pudimos tener hoy que es sumamente placentero porque es un crecer y es una mirada y una puesta en marcha absolutamente diferente, en alg\u00fan momento pudimos decir somos la tercera fuerza\u00a0 pol\u00edtica hoy podemos decir que somos la \u00fanica fuerza pol\u00edtica que muestra y separa con toda la valent\u00eda en la b\u00fasqueda de alg\u00fan horizonte que nos lleve a encontrar soluciones concretas a los problemas que ya todos sabemos que tenemos&#8221;.<\/p>\n<p><a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/randazzo-3\/\" rel=\"attachment wp-att-154534\"><img decoding=\"async\" class=\"alignnone size-full wp-image-154534\" src=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo.jpg\" alt=\"Randazzo\" width=\"765\" height=\"510\" srcset=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo.jpg 765w, https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-300x200.jpg 300w\" sizes=\"(max-width: 765px) 100vw, 765px\" \/><\/a><\/p>\n<p>&#8220;En base a distintas cuestiones que tambi\u00e9n han sucedido y han sido de p\u00fablico conocimiento y sabiendo que vengo de ese peronismo tradicional de la provincia, ese peronismo que no traiciona, que tiene una doctrina marcada que habla de inclusi\u00f3n social nunca de exclusi\u00f3n, siempre habla de acci\u00f3n social&#8221;.<\/p>\n<p>Luego tom\u00f3 la palabra Randazzo quien cont\u00f3 acerca del encuentro &#8220;repasamos diferentes temas, pero lo m\u00e1s importante es que hemos trabajado fundamentalmente en los temas que son la preocupaci\u00f3n en la sociedad y que es com\u00fan en toda la provincia. En todas las reuniones encontramos tres problemas la falta de trabajo, tambi\u00e9n en los servicios p\u00fablicos, la educaci\u00f3n, seguridad&#8221;.<\/p>\n<p>Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, Randazzo finaliz\u00f3 &#8220;tenemos una evaluaci\u00f3n de lo que pas\u00f3, estamos convencidos de que este a\u00f1o y medio el actual Gobierno err\u00f3 en todas sus pol\u00edticas, no cumpli\u00f3 las promesas hasta el manejo de la pandemia, la idea de la dicotom\u00eda de salud-econom\u00eda, se destruy\u00f3 la econom\u00eda y muri\u00f3 gente, hubo errores que fueron importantes. Nos costaba pensar que el voto de castigo iba a ir a quienes fracasaron hace un a\u00f1o y medio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde&#8230;<\/p>\n","protected":false},"author":1,"featured_media":154528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[51,43],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro<\/title>\n<meta name=\"description\" content=\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se hizo conferencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro\" \/>\n<meta property=\"og:description\" content=\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se hizo conferencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T23:08:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-13T23:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"765\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel\",\"datePublished\":\"2021-10-13T23:08:31+00:00\",\"dateModified\":\"2021-10-13T23:43:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\"},\"wordCount\":713,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Destacadas\",\"Pol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\",\"name\":\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-10-13T23:08:31+00:00\",\"dateModified\":\"2021-10-13T23:43:44+00:00\",\"description\":\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se hizo conferencia.\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro","description":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se hizo conferencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/","og_locale":"es_ES","og_type":"article","og_title":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro","og_description":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se hizo conferencia.","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-10-13T23:08:31+00:00","article_modified_time":"2021-10-13T23:43:44+00:00","og_image":[{"width":765,"height":510,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel","datePublished":"2021-10-13T23:08:31+00:00","dateModified":"2021-10-13T23:43:44+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/"},"wordCount":713,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Destacadas","Pol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/","name":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-10-13T23:08:31+00:00","dateModified":"2021-10-13T23:43:44+00:00","description":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel, en la tarde de este mi\u00e9rcoles se hizo conferencia.","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/randazzo-estuvo-en-olavarria-junto-a-carolina-castro-respaldando-a-andrea-coronel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Randazzo estuvo en Olavarr\u00eda junto a Carolina Castro respaldando a Andrea Coronel"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",765,510,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria-300x200.jpg",300,200,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",640,427,false],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",640,427,false],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",765,510,false],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",765,510,false],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",765,510,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",765,510,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",765,510,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",713,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",640,427,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Randazzo-en-Olavarria.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/politica\/\" rel=\"category tag\">Pol\u00edtica<\/a>","tag_info":"Pol\u00edtica","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154527"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=154527"}],"version-history":[{"count":7,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154527\/revisions"}],"predecessor-version":[{"id":154542,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/154527\/revisions\/154542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/154528"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=154527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=154527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=154527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}