{"id":153832,"date":"2021-10-02T11:27:43","date_gmt":"2021-10-02T14:27:43","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=153832"},"modified":"2021-10-02T11:34:32","modified_gmt":"2021-10-02T14:34:32","slug":"la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/","title":{"rendered":"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal"},"content":{"rendered":"<p>La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos para Personas con Discapacidad y Personas Mayores, informa que a partir del lunes 4 de octubre comenzar\u00e1 la atenci\u00f3n presencial de la Junta Evaluadora de Discapacidad que funciona en el Box 3 y consultorios 14 y 15 del Hospital Municipal \u201cDr. H\u00e9ctor Cura\u201d.<\/p>\n<p>La Junta Evaluadora es el espacio interdisciplinario que se encarga de otorgar los CUD: (certificados \u00fanicos de discapacidad) a aquellas personas que lo solicitan, mediante diferentes evaluaciones a los fines de determinar si corresponde la emisi\u00f3n de dicho certificado, que le permite a las personas beneficiarias acceder a diversas prestaciones de salud y seguridad social.<\/p>\n<p>La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, Desde el Programa de Promoci\u00f3n de Derechos para Personas con Discapacidad y Personas Mayores comunican que se pondr\u00e1n en contacto con quienes hayan iniciado los expedientes para su tramitaci\u00f3n, para programar los turnos de atenci\u00f3n.<\/p>\n<p>Por consultas e inquietudes, comunicarse de lunes a viernes de 7 a 13 horas a los tel\u00e9fonos 428333 o 419561, o dirigirse a la sede de Av. Sarmiento 2458.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":112201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[51,45],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La junta evaluadora retoma su esquema de atenci\u00f3n habitual<\/title>\n<meta name=\"description\" content=\"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La junta evaluadora retoma su esquema de atenci\u00f3n habitual\" \/>\n<meta property=\"og:description\" content=\"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-02T14:27:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-02T14:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal\",\"datePublished\":\"2021-10-02T14:27:43+00:00\",\"dateModified\":\"2021-10-02T14:34:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Destacadas\",\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\",\"name\":\"La junta evaluadora retoma su esquema de atenci\u00f3n habitual\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-10-02T14:27:43+00:00\",\"dateModified\":\"2021-10-02T14:34:32+00:00\",\"description\":\"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La junta evaluadora retoma su esquema de atenci\u00f3n habitual","description":"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/","og_locale":"es_ES","og_type":"article","og_title":"La junta evaluadora retoma su esquema de atenci\u00f3n habitual","og_description":"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-10-02T14:27:43+00:00","article_modified_time":"2021-10-02T14:34:32+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal","datePublished":"2021-10-02T14:27:43+00:00","dateModified":"2021-10-02T14:34:32+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/"},"wordCount":213,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Destacadas","Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/","name":"La junta evaluadora retoma su esquema de atenci\u00f3n habitual","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-10-02T14:27:43+00:00","dateModified":"2021-10-02T14:34:32+00:00","description":"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal, a trav\u00e9s del Programa de Promoci\u00f3n de Derechos","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/la-junta-evaluadora-retoma-su-esquema-de-atencion-habitual-en-el-hospital-municipal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"La Junta Evaluadora retoma su esquema de atenci\u00f3n habitual en el Hospital Municipal"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",800,533,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa-300x200.jpg",300,200,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa-768x512.jpg",640,427,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",640,426,false],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa-768x512.jpg",768,512,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",800,533,false],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",800,533,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",800,533,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",800,533,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",713,475,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",640,426,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",96,64,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2020\/06\/Hospital_municipal_covid_tapa.jpg",150,100,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/salud\/\" rel=\"category tag\">Salud<\/a>","tag_info":"Salud","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/153832"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=153832"}],"version-history":[{"count":2,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/153832\/revisions"}],"predecessor-version":[{"id":153834,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/153832\/revisions\/153834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/112201"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=153832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=153832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=153832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}