{"id":153801,"date":"2021-10-01T19:16:27","date_gmt":"2021-10-01T22:16:27","guid":{"rendered":"https:\/\/experienciadevida.com.ar\/portalurbano\/?p=153801"},"modified":"2021-10-01T19:18:59","modified_gmt":"2021-10-01T22:18:59","slug":"mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta","status":"publish","type":"post","link":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/","title":{"rendered":"Mauricio Dilascio: &#8220;Es importante realizar los controles de rutina en la infancia y en la vida adulta&#8221;"},"content":{"rendered":"<p>Mauricio Dilascio: &#8220;Es importante realizar los controles de rutina en la infancia y en la vida adulta&#8221;, as\u00ed lo dijo el Doctor en di\u00e1logo con este medio en el marco del mes del coraz\u00f3n que finaliz\u00f3 el d\u00eda de ayer, aunque los especialistas mencionan que el d\u00eda del coraz\u00f3n son los 365 del a\u00f1o.<\/p>\n<p>En cuanto a las enfermedades cardiovasculares que existen el doctor explic\u00f3 &#8220;las enfermedades m\u00e1s frecuentes son las cardiopat\u00edas cong\u00e9nitas en la infancia y la cardiopat\u00eda isqu\u00e9mica (falta de irrigaci\u00f3n del coraz\u00f3n por oclusi\u00f3n de las arterias coronarias)&#8221; &#8220;y son la primer causa de muerte en el mundo&#8221;.<\/p>\n<p>&#8220;Una cardiopat\u00eda cong\u00e9nita son defectos en la estructura del coraz\u00f3n que se producen durante su formaci\u00f3n. No se deben en su mayor\u00eda a ninguna enfermedad asociada sino a una alteraci\u00f3n al &#8220;azar&#8221; durante la gestaci\u00f3n, es la m\u00e1s frecuente estando presente en 1 de cada 100 nacimientos&#8221;, a su vez &#8220;se pueden detectar durante el embarazo mediante una ecograf\u00eda del coraz\u00f3n del beb\u00e9 o luego del nacimiento si el reci\u00e9n nacido presenta s\u00edntomas (soplo, cambios de coloraci\u00f3n, cansancio, problemas de crecimiento). Otras menos severas pueden diagnosticarse de adultos en ex\u00e1menes de rutina&#8221;, mencion\u00f3 el doctor Mauricio Dilascio.<\/p>\n<p>En cuanto a los tratamientos dijo &#8220;se pueden realizar intervenciones por cateterismo o cirug\u00eda, otras no requieren tratamiento y solo se controlan. La mayor\u00eda puede realizar una vida normal con un tratamiento adecuado&#8221;, adem\u00e1s &#8220;el diagn\u00f3stico fetal es importante para las patolog\u00edas m\u00e1s graves que requieren intervenci\u00f3n en los primeros d\u00edas de vida ya que en Argentina estos procedimientos se realizan en pocos lugares y nos permite que el nacimiento de un beb\u00e9 portador de una cardiopat\u00eda sea en el lugar y momento adecuado. En Olavarr\u00eda tenemos muchos pacientes en seguimiento ya operados (entre 10 y 15) con patolog\u00edas severas detectadas en la panza de la mam\u00e1&#8221;.<\/p>\n<p>Tras el regreso a la nueva normalidad mencion\u00f3 que los pacientes se volvieron a controlar &#8220;luego de un a\u00f1o en que no lo hicieron pueden controlarse, actualmente con la vacunaci\u00f3n ya pueden retomar los controles a su vez se va normalizando los procedimientos\u00a0 y controles en los centros de Buenos Aires y La Plata, estamos haciendo lo que no se pudo en el 2020&#8221;.<\/p>\n<p>En cuanto a volver a tener una vida social Mauricio Dilascio mencion\u00f3 &#8220;el objetivo de nuestro trabajo es poder brindarle a nuestros pacientes una vida lo m\u00e1s normal posible. Todo depende del riesgo individual y si est\u00e1n vacunados o no, algunos a\u00fan no lo han podido realizar pero los que s\u00ed pueden que lo hagan y realicen actividad f\u00edsica&#8221;.<\/p>\n<p>Con respecto a la actividad f\u00edsica &#8220;lo importante es estar en movimiento y disminuir el sedentarismo y las pantallas, asique en principio cualquier tipo de actividad es bienvenida. Se recomienda al menos 30 minutos de actividad diaria, desde el juego en ni\u00f1os hasta la actividad deportiva m\u00e1s organizada y competitiva en mayores es importante&#8221;.<\/p>\n<p>Para finalizar &#8220;el mensaje que se trata de dar en los \u00faltimos a\u00f1os es el de la prevenci\u00f3n desde la infancia, llevando h\u00e1bitos saludables. Hay que mejorar los h\u00e1bitos alimenticios, estar m\u00e1s activos, tambi\u00e9n es importante realizar los controles en la infancia y en la vida adulta&#8221;.<\/p>\n<p>Foto: Facebook<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mauricio Dilascio: &#8220;Es importante realizar los controles de rutina en la infancia y en la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":153805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[27,51],"tags":[],"nelio_content":{"isAutoShareEnabled":false,"autoShareEndMode":"default","automationSources":{"useContentSentences":true,"useSocialTemplates":true,"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":"","highlights":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mauricio Dilascio: &quot;Es importante realizar los controles de rutina en la infancia<\/title>\n<meta name=\"description\" content=\"Mauricio Dilascio: &quot;Es importante realizar los controles de rutina en la infancia y en la vida adulta&quot;, as\u00ed lo dijo el Doctor en di\u00e1logo con este medio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mauricio Dilascio: &quot;Es importante realizar los controles de rutina en la infancia\" \/>\n<meta property=\"og:description\" content=\"Mauricio Dilascio: &quot;Es importante realizar los controles de rutina en la infancia y en la vida adulta&quot;, as\u00ed lo dijo el Doctor en di\u00e1logo con este medio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T22:16:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T22:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admpu17wp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:site\" content=\"@portalurbanook\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admpu17wp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\"},\"author\":{\"name\":\"admpu17wp\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\"},\"headline\":\"Mauricio Dilascio: &#8220;Es importante realizar los controles de rutina en la infancia y en la vida adulta&#8221;\",\"datePublished\":\"2021-10-01T22:16:27+00:00\",\"dateModified\":\"2021-10-01T22:18:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"articleSection\":[\"Ciudad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\",\"name\":\"Mauricio Dilascio: \\\"Es importante realizar los controles de rutina en la infancia\",\"isPartOf\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\"},\"datePublished\":\"2021-10-01T22:16:27+00:00\",\"dateModified\":\"2021-10-01T22:18:59+00:00\",\"description\":\"Mauricio Dilascio: \\\"Es importante realizar los controles de rutina en la infancia y en la vida adulta\\\", as\u00ed lo dijo el Doctor en di\u00e1logo con este medio\",\"breadcrumb\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mauricio Dilascio: \u00abEs importante realizar los controles de rutina en la infancia y en la vida adulta\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#website\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization\",\"name\":\"Portal Urbano\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"contentUrl\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png\",\"width\":2236,\"height\":1216,\"caption\":\"Portal Urbano\"},\"image\":{\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/\",\"https:\/\/twitter.com\/portalurbanook\",\"https:\/\/www.instagram.com\/_portalurbano\/\",\"https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7\",\"name\":\"admpu17wp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g\",\"caption\":\"admpu17wp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mauricio Dilascio: \"Es importante realizar los controles de rutina en la infancia","description":"Mauricio Dilascio: \"Es importante realizar los controles de rutina en la infancia y en la vida adulta\", as\u00ed lo dijo el Doctor en di\u00e1logo con este medio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/","og_locale":"es_ES","og_type":"article","og_title":"Mauricio Dilascio: \"Es importante realizar los controles de rutina en la infancia","og_description":"Mauricio Dilascio: \"Es importante realizar los controles de rutina en la infancia y en la vida adulta\", as\u00ed lo dijo el Doctor en di\u00e1logo con este medio","og_url":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/","article_publisher":"https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","article_published_time":"2021-10-01T22:16:27+00:00","article_modified_time":"2021-10-01T22:18:59+00:00","og_image":[{"width":800,"height":505,"url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg","type":"image\/jpeg"}],"author":"admpu17wp","twitter_card":"summary_large_image","twitter_creator":"@portalurbanook","twitter_site":"@portalurbanook","twitter_misc":{"Escrito por":"admpu17wp","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/#article","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/"},"author":{"name":"admpu17wp","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7"},"headline":"Mauricio Dilascio: &#8220;Es importante realizar los controles de rutina en la infancia y en la vida adulta&#8221;","datePublished":"2021-10-01T22:16:27+00:00","dateModified":"2021-10-01T22:18:59+00:00","mainEntityOfPage":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/"},"wordCount":595,"publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"articleSection":["Ciudad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/","name":"Mauricio Dilascio: \"Es importante realizar los controles de rutina en la infancia","isPartOf":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website"},"datePublished":"2021-10-01T22:16:27+00:00","dateModified":"2021-10-01T22:18:59+00:00","description":"Mauricio Dilascio: \"Es importante realizar los controles de rutina en la infancia y en la vida adulta\", as\u00ed lo dijo el Doctor en di\u00e1logo con este medio","breadcrumb":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/mauricio-dilascio-es-importante-realizar-los-controles-de-rutina-en-la-infancia-y-en-la-vida-adulta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/experienciadevida.com.ar\/portalurbano\/"},{"@type":"ListItem","position":2,"name":"Mauricio Dilascio: \u00abEs importante realizar los controles de rutina en la infancia y en la vida adulta\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#website","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","name":"","description":"","publisher":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienciadevida.com.ar\/portalurbano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#organization","name":"Portal Urbano","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/","url":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","contentUrl":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2019\/09\/Logo-Original.png","width":2236,"height":1216,"caption":"Portal Urbano"},"image":{"@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Portal-Urbano-171542830093757\/","https:\/\/twitter.com\/portalurbanook","https:\/\/www.instagram.com\/_portalurbano\/","https:\/\/www.youtube.com\/channel\/UCXhagIfszH8KxFiOok79zbA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/02dd326b1c4b056e9cc972486934a3a7","name":"admpu17wp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/experienciadevida.com.ar\/portalurbano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830d4c57adaae6630765e449a6908047?s=96&d=mm&r=g","caption":"admpu17wp"}}]}},"featured_image_urls":{"full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",800,505,false],"thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-150x150.jpg",150,150,true],"medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-300x189.jpg",300,189,true],"medium_large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-768x484.jpg",640,403,true],"large":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-1024x646.jpg",640,404,true],"ug_big":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-768x484.jpg",768,484,true],"1536x1536":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",800,505,false],"2048x2048":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",800,505,false],"newsever-slider-full":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",800,505,false],"newsever-featured":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",800,505,false],"newsever-medium":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",720,455,false],"web-stories-poster-portrait":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",640,404,false],"web-stories-publisher-logo":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",96,61,false],"web-stories-thumbnail":["https:\/\/experienciadevida.com.ar\/portalurbano\/wp-content\/uploads\/2021\/10\/Mauricio-Dilascio-e1633126659538.jpg",150,95,false]},"author_info":{"display_name":"admpu17wp","author_link":"https:\/\/experienciadevida.com.ar\/portalurbano\/author\/admpu17wp\/"},"category_info":"<a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/ciudad\/\" rel=\"category tag\">Ciudad<\/a> <a href=\"https:\/\/experienciadevida.com.ar\/portalurbano\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a>","tag_info":"Destacadas","comment_count":"0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/153801"}],"collection":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/comments?post=153801"}],"version-history":[{"count":3,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/153801\/revisions"}],"predecessor-version":[{"id":153806,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/posts\/153801\/revisions\/153806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media\/153805"}],"wp:attachment":[{"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/media?parent=153801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/categories?post=153801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienciadevida.com.ar\/portalurbano\/wp-json\/wp\/v2\/tags?post=153801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}